{"id":10442,"date":"2025-03-21T14:07:30","date_gmt":"2025-03-21T13:07:30","guid":{"rendered":"https:\/\/nutzfahrzeugtechnik.org\/vehicles\/unimog\/u200\/"},"modified":"2025-03-21T14:07:30","modified_gmt":"2025-03-21T13:07:30","slug":"u200","status":"publish","type":"page","link":"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/","title":{"rendered":"U200"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":10436,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10442","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rotachain automatic snow chains for Unimog U200<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rotachain automatic snow chains for Unimog U200\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/\" \/>\n<meta property=\"og:site_name\" content=\"Schleuderketten Rotationsketten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/\",\"url\":\"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/\",\"name\":\"Rotachain automatic snow chains for Unimog U200\",\"isPartOf\":{\"@id\":\"https:\/\/www.schleuderkette.de\/en\/#website\"},\"datePublished\":\"2025-03-21T13:07:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.schleuderkette.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equippable vehicles\",\"item\":\"https:\/\/www.schleuderkette.de\/en\/vehicles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unimog\",\"item\":\"https:\/\/rotationsketten.com\/en\/vehicles\/unimog\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"U200\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.schleuderkette.de\/en\/#website\",\"url\":\"https:\/\/www.schleuderkette.de\/en\/\",\"name\":\"Schleuderketten Rotationsketten\",\"description\":\"Rotachain f\u00fcr Nutzfahrzeuge wie MAN, Mercedes Benz, Iveco, Scania, Renault, DAF\",\"publisher\":{\"@id\":\"https:\/\/www.schleuderkette.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.schleuderkette.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.schleuderkette.de\/en\/#organization\",\"name\":\"Schleuderketten Rotationsketten\",\"url\":\"https:\/\/www.schleuderkette.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.schleuderkette.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/anfahrhilfen.de\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png\",\"contentUrl\":\"https:\/\/anfahrhilfen.de\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png\",\"width\":423,\"height\":256,\"caption\":\"Schleuderketten Rotationsketten\"},\"image\":{\"@id\":\"https:\/\/www.schleuderkette.de\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rotachain automatic snow chains for Unimog U200","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/","og_locale":"en_US","og_type":"article","og_title":"Rotachain automatic snow chains for Unimog U200","og_url":"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/","og_site_name":"Schleuderketten Rotationsketten","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/","url":"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/","name":"Rotachain automatic snow chains for Unimog U200","isPartOf":{"@id":"https:\/\/www.schleuderkette.de\/en\/#website"},"datePublished":"2025-03-21T13:07:30+00:00","breadcrumb":{"@id":"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/anfahrhilfen.de\/en\/vehicles\/unimog\/u200\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.schleuderkette.de\/en\/"},{"@type":"ListItem","position":2,"name":"Equippable vehicles","item":"https:\/\/www.schleuderkette.de\/en\/vehicles\/"},{"@type":"ListItem","position":3,"name":"Unimog","item":"https:\/\/rotationsketten.com\/en\/vehicles\/unimog\/"},{"@type":"ListItem","position":4,"name":"U200"}]},{"@type":"WebSite","@id":"https:\/\/www.schleuderkette.de\/en\/#website","url":"https:\/\/www.schleuderkette.de\/en\/","name":"Schleuderketten Rotationsketten","description":"Rotachain f\u00fcr Nutzfahrzeuge wie MAN, Mercedes Benz, Iveco, Scania, Renault, DAF","publisher":{"@id":"https:\/\/www.schleuderkette.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schleuderkette.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.schleuderkette.de\/en\/#organization","name":"Schleuderketten Rotationsketten","url":"https:\/\/www.schleuderkette.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.schleuderkette.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/anfahrhilfen.de\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png","contentUrl":"https:\/\/anfahrhilfen.de\/wp-content\/uploads\/2024\/05\/rota_chain_Logo-2-1.png","width":423,"height":256,"caption":"Schleuderketten Rotationsketten"},"image":{"@id":"https:\/\/www.schleuderkette.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/anfahrhilfen.de\/en\/wp-json\/wp\/v2\/pages\/10442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anfahrhilfen.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anfahrhilfen.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anfahrhilfen.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anfahrhilfen.de\/en\/wp-json\/wp\/v2\/comments?post=10442"}],"version-history":[{"count":0,"href":"https:\/\/anfahrhilfen.de\/en\/wp-json\/wp\/v2\/pages\/10442\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/anfahrhilfen.de\/en\/wp-json\/wp\/v2\/pages\/10436"}],"wp:attachment":[{"href":"https:\/\/anfahrhilfen.de\/en\/wp-json\/wp\/v2\/media?parent=10442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}